{"id":6912,"date":"2023-09-22T15:40:25","date_gmt":"2023-09-22T18:40:25","guid":{"rendered":"https:\/\/terrantai.com\/?p=6912"},"modified":"2025-03-06T14:30:32","modified_gmt":"2025-03-06T14:30:32","slug":"tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan","status":"publish","type":"post","link":"http:\/\/terrantai.com\/pt\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/","title":{"rendered":"Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"6912\" class=\"elementor elementor-6912\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-add4623 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"add4623\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ec0aa4\" data-id=\"6ec0aa4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e173464 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e173464\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/terrantai.com\/pt\/san-pedro-de-atacama-un-oasis-en-el-desierto\/\">\n\t\t\t\t\t\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/03\/12-09.png?w=800\" title=\"\" alt=\"Terrantai-ES\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b2a3dc elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"6b2a3dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/terrantai.com\/en\/terrantai-lodge-en\/\">\n\t\t\t\t\t\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/03\/12-11.png?w=800\" title=\"\" alt=\"Terrantai-EN\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b848ae6 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"b848ae6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/terrantai.com\/pt\/pt-pt\/san-pedro-de-atacama-um-oasis-no-meio-do-deserto\/\">\n\t\t\t\t\t\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/03\/12-10.png?w=800\" title=\"\" alt=\"Terranati PT\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1869a59 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1869a59\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26b0590 elementor-widget-mobile__width-initial elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"26b0590\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3af1ca0 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3af1ca0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"wp-image-6914 alignright\" src=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-Foto-2.jpg?resize=360%2C240\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-Foto-2.jpg?w=1500 1500w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-Foto-2.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-Foto-2.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-Foto-2.jpg?resize=768%2C512 768w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/>La Fiesta de la Virgen de Ayquina es una de las celebraciones m\u00e1s emblem\u00e1ticas y emocionantes de la segunda regi\u00f3n de Chile. Cada a\u00f1o, miles de peregrinos (caminantes y bailarines) y visitantes se re\u00fanen en este remoto pueblo del norte de Chile para rendir homenaje a la Virgen de Ayquina y participar en una festividad llena de color, m\u00fasica y espiritualidad. Ayquina es un pueblo ubicado en la provincia del Loa, II Regi\u00f3n de Antofagasta, a 150km de San Pedro de Atacama, un viaje en auto de aproximadamente 1h30. Exploraremos ac\u00e1 un poco m\u00e1s de la historia y las tradiciones de esta festividad \u00fanica, que combina la fe religiosa con la cultura chilena y dejaremos nuestro sencillo homenaje a esta celebraci\u00f3n tan bonita.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:image {\"id\":6914,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<p><!-- \/wp:image --><!-- wp:paragraph --><\/p>\n<p><strong>Historia de la Virgen de Ayquina<\/strong><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Un ni\u00f1o pastor llamado Casimiro Saire, el 12 de diciembre de 1646 vio aparecer una mujer la cual se hizo su amiga, cuando los adultos llegaron al lugar encontraron una peque\u00f1a imagen de la Virgen, reaccionaron con fervor religioso y decidieron instalar la imagen sagrada en las ruinas de una capilla cercana. La virgen de Ayquina es considerada la patrona de los mineros de Chuquicamata, por lo que un gran n\u00famero de ellos acuden cada a\u00f1o a su celebraci\u00f3n.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"wp-image-6916 alignleft\" src=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-3.jpg?resize=320%2C569\" alt=\"\" width=\"320\" height=\"569\" srcset=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-3.jpg?w=1000 1000w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-3.jpg?resize=169%2C300 169w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-3.jpg?resize=576%2C1024 576w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-3.jpg?resize=768%2C1366 768w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-3.jpg?resize=864%2C1536 864w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/p>\n<p><strong>La Fiesta de la Virgen de Ayquina<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<div class=\"wp-block-column\"><!-- wp:image {\"id\":6916,\"width\":354,\"height\":629,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-large is-resized\">La fiesta se celebra cada 8 de septiembre, en honor a la Virgen de Ayquina. Las festividades comienzan con el peregrinar de fieles caminantes que a\u00f1o tras a\u00f1o, cumplen su manda caminando por el desierto desde la ciudad de Calama hasta el poblado de Ayquina.<\/figure>\n<\/div>\n<p><!-- wp:paragraph --><\/p>\n<p>Desde el d\u00eda 1 al 4 de septiembre los bailes religiosos realizan su entrada para saludar a la Virgen de Ayquina, para dar as\u00ed comienzo a lo que ser\u00e1n cinco d\u00edas de fiesta en donde un aproximado de 50 bailes acompa\u00f1ados de sus bandas de bronces, danzan d\u00eda y noche para cumplir un a\u00f1o m\u00e1s con la \u201cchinita\u201d que cari\u00f1osamente la llaman sus fieles devotos. El d\u00eda 8 de septiembre se lleva a cabo una procesi\u00f3n en la que la imagen de la Virgen es llevada en andas por las calles del pueblo, acompa\u00f1ada por m\u00fasicos y bailarines tradicionales. La m\u00fasica y la danza son elementos esenciales de la celebraci\u00f3n en donde llenan de color, devoci\u00f3n y alegr\u00eda el peque\u00f1o pueblo de Ayquina.<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"wp-image-6917 alignright\" src=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-4.jpg?resize=329%2C493\" alt=\"\" width=\"329\" height=\"493\" srcset=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-4.jpg?w=1000 1000w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-4.jpg?resize=200%2C300 200w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-4.jpg?resize=683%2C1024 683w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-4.jpg?resize=768%2C1152 768w\" sizes=\"auto, (max-width: 329px) 100vw, 329px\" \/>Los Bailes Religiosos<\/strong><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Una de las tradiciones m\u00e1s destacadas de la Fiesta de la Virgen de Ayquina son los bailes religiosos. Grupos de bailarines, vestidos con trajes coloridos y caretas (m\u00e1scaras), danzan en honor a la Virgen. Cada grupo representa una historia religiosa o un aspecto de la vida en el desierto de Atacama. Los bailes son una forma de expresi\u00f3n art\u00edstica y espiritual que conecta a la comunidad con su herencia y fe.<\/p>\n<p><!-- \/wp:paragraph --><!-- \/wp:column --><!-- wp:column {\"width\":\"33.33%\"} --><\/p>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" class=\"wp-image-6919 alignright\" src=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-6.jpg?resize=360%2C240\" alt=\"\" width=\"360\" height=\"240\" srcset=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-6.jpg?w=1500 1500w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-6.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-6.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-6.jpg?resize=768%2C512 768w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/div>\n<div class=\"wp-block-column\" style=\"flex-basis: 33.33%;\"><strong>La Fiesta Contin\u00faa<\/strong><\/div>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>La Fiesta de la Virgen de Ayquina es un evento que combina la religi\u00f3n, la cultura y la tradici\u00f3n en un ambiente festivo y lleno de alegr\u00eda. Es una experiencia \u00fanica que muestra la profunda conexi\u00f3n entre la fe y la vida cotidiana en el norte de Chile. Si alguna vez tienes la oportunidad de visitar Ayquina en septiembre, no te pierdas esta celebraci\u00f3n que te dejar\u00e1 con recuerdos imborrables y una apreciaci\u00f3n renovada por la diversidad cultural de Chile. \u00a1Viva la Virgen de Ayquina!<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:image {\"id\":6919,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<p>\u00a0<\/p>\n<p>\ud83c\udf35\ud83c\udf38\ud83c\udf05<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La Fiesta de la Virgen de Ayquina es una de las celebraciones m\u00e1s emblem\u00e1ticas y emocionantes de la segunda regi\u00f3n de Chile. Cada a\u00f1o, miles de peregrinos (caminantes y bailarines) y visitantes se re\u00fanen en este remoto pueblo del norte de Chile para rendir homenaje a la Virgen de Ayquina y participar en una festividad llena de color, m\u00fasica y espiritualidad. Ayquina es un pueblo ubicado en la provincia del Loa, II Regi\u00f3n de Antofagasta, a 150km de San Pedro de Atacama, un viaje en auto de aproximadamente 1h30.<\/p>","protected":false},"author":2,"featured_media":6913,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[85,87,89,66],"class_list":["post-6912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-ceremonias","tag-festividad-local","tag-ritual","tag-san-pedro-de-atacama"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/terrantai.com\/pt\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina -\" \/>\n<meta property=\"og:description\" content=\"La Fiesta de la Virgen de Ayquina es una de las celebraciones m\u00e1s emblem\u00e1ticas y emocionantes de la segunda regi\u00f3n de Chile. Cada a\u00f1o, miles de peregrinos (caminantes y bailarines) y visitantes se re\u00fanen en este remoto pueblo del norte de Chile para rendir homenaje a la Virgen de Ayquina y participar en una festividad llena de color, m\u00fasica y espiritualidad. Ayquina es un pueblo ubicado en la provincia del Loa, II Regi\u00f3n de Antofagasta, a 150km de San Pedro de Atacama, un viaje en auto de aproximadamente 1h30.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/terrantai.com\/pt\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-22T18:40:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-06T14:30:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-1-1.jpg?fit=2000%2C1333&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hotel Terrantai\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hotel Terrantai\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/\"},\"author\":{\"name\":\"Hotel Terrantai\",\"@id\":\"https:\\\/\\\/terrantai.com\\\/es\\\/#\\\/schema\\\/person\\\/acd1931cee19c047e1c8be6e9a770098\"},\"headline\":\"Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina\",\"datePublished\":\"2023-09-22T18:40:25+00:00\",\"dateModified\":\"2025-03-06T14:30:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/\"},\"wordCount\":606,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/terrantai.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Blog-foto-1-1.jpg?fit=2000%2C1333\",\"keywords\":[\"Ceremonias\",\"Festividad local\",\"Ritual\",\"san pedro de atacama\"],\"articleSection\":[\"Blog | ES\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/\",\"url\":\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/\",\"name\":\"Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/terrantai.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/terrantai.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Blog-foto-1-1.jpg?fit=2000%2C1333\",\"datePublished\":\"2023-09-22T18:40:25+00:00\",\"dateModified\":\"2025-03-06T14:30:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/terrantai.com\\\/es\\\/#\\\/schema\\\/person\\\/acd1931cee19c047e1c8be6e9a770098\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/terrantai.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Blog-foto-1-1.jpg?fit=2000%2C1333\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/terrantai.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Blog-foto-1-1.jpg?fit=2000%2C1333\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/terrantai.com\\\/en\\\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/terrantai.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/terrantai.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/terrantai.com\\\/es\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/terrantai.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/terrantai.com\\\/es\\\/#\\\/schema\\\/person\\\/acd1931cee19c047e1c8be6e9a770098\",\"name\":\"Hotel Terrantai\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/terrantai.com\\\/wp-content\\\/litespeed\\\/avatar\\\/5cfa6f23b7e2afd63de105841326db52.jpg?ver=1778285903\",\"url\":\"http:\\\/\\\/terrantai.com\\\/wp-content\\\/litespeed\\\/avatar\\\/5cfa6f23b7e2afd63de105841326db52.jpg?ver=1778285903\",\"contentUrl\":\"http:\\\/\\\/terrantai.com\\\/wp-content\\\/litespeed\\\/avatar\\\/5cfa6f23b7e2afd63de105841326db52.jpg?ver=1778285903\",\"caption\":\"Hotel Terrantai\"},\"url\":\"http:\\\/\\\/terrantai.com\\\/pt\\\/author\\\/admin-terrantai\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/terrantai.com\/pt\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/","og_locale":"pt_BR","og_type":"article","og_title":"Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina -","og_description":"La Fiesta de la Virgen de Ayquina es una de las celebraciones m\u00e1s emblem\u00e1ticas y emocionantes de la segunda regi\u00f3n de Chile. Cada a\u00f1o, miles de peregrinos (caminantes y bailarines) y visitantes se re\u00fanen en este remoto pueblo del norte de Chile para rendir homenaje a la Virgen de Ayquina y participar en una festividad llena de color, m\u00fasica y espiritualidad. Ayquina es un pueblo ubicado en la provincia del Loa, II Regi\u00f3n de Antofagasta, a 150km de San Pedro de Atacama, un viaje en auto de aproximadamente 1h30.","og_url":"https:\/\/terrantai.com\/pt\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/","article_published_time":"2023-09-22T18:40:25+00:00","article_modified_time":"2025-03-06T14:30:32+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-1-1.jpg?fit=2000%2C1333&ssl=1","type":"image\/jpeg"}],"author":"Hotel Terrantai","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Hotel Terrantai","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/#article","isPartOf":{"@id":"https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/"},"author":{"name":"Hotel Terrantai","@id":"https:\/\/terrantai.com\/es\/#\/schema\/person\/acd1931cee19c047e1c8be6e9a770098"},"headline":"Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina","datePublished":"2023-09-22T18:40:25+00:00","dateModified":"2025-03-06T14:30:32+00:00","mainEntityOfPage":{"@id":"https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/"},"wordCount":606,"commentCount":0,"image":{"@id":"https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-1-1.jpg?fit=2000%2C1333","keywords":["Ceremonias","Festividad local","Ritual","san pedro de atacama"],"articleSection":["Blog | ES"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/","url":"https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/","name":"Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina -","isPartOf":{"@id":"https:\/\/terrantai.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/#primaryimage"},"image":{"@id":"https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-1-1.jpg?fit=2000%2C1333","datePublished":"2023-09-22T18:40:25+00:00","dateModified":"2025-03-06T14:30:32+00:00","author":{"@id":"https:\/\/terrantai.com\/es\/#\/schema\/person\/acd1931cee19c047e1c8be6e9a770098"},"breadcrumb":{"@id":"https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/#primaryimage","url":"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-1-1.jpg?fit=2000%2C1333","contentUrl":"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-1-1.jpg?fit=2000%2C1333","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/terrantai.com\/en\/tradicion-y-devocion-la-fiesta-de-la-virgen-de-ayquinan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/terrantai.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tradici\u00f3n y Devoci\u00f3n | La Fiesta de la Virgen de Ayquina"}]},{"@type":"WebSite","@id":"https:\/\/terrantai.com\/es\/#website","url":"https:\/\/terrantai.com\/es\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/terrantai.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/terrantai.com\/es\/#\/schema\/person\/acd1931cee19c047e1c8be6e9a770098","name":"Hotel Terrantai","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/terrantai.com\/wp-content\/litespeed\/avatar\/5cfa6f23b7e2afd63de105841326db52.jpg?ver=1778285903","url":"http:\/\/terrantai.com\/wp-content\/litespeed\/avatar\/5cfa6f23b7e2afd63de105841326db52.jpg?ver=1778285903","contentUrl":"http:\/\/terrantai.com\/wp-content\/litespeed\/avatar\/5cfa6f23b7e2afd63de105841326db52.jpg?ver=1778285903","caption":"Hotel Terrantai"},"url":"http:\/\/terrantai.com\/pt\/author\/admin-terrantai\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/terrantai.com\/wp-content\/uploads\/2023\/09\/Blog-foto-1-1.jpg?fit=2000%2C1333","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/terrantai.com\/pt\/wp-json\/wp\/v2\/posts\/6912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/terrantai.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/terrantai.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/terrantai.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/terrantai.com\/pt\/wp-json\/wp\/v2\/comments?post=6912"}],"version-history":[{"count":0,"href":"http:\/\/terrantai.com\/pt\/wp-json\/wp\/v2\/posts\/6912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/terrantai.com\/pt\/wp-json\/wp\/v2\/media\/6913"}],"wp:attachment":[{"href":"http:\/\/terrantai.com\/pt\/wp-json\/wp\/v2\/media?parent=6912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/terrantai.com\/pt\/wp-json\/wp\/v2\/categories?post=6912"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/terrantai.com\/pt\/wp-json\/wp\/v2\/tags?post=6912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}